{"id":4877,"date":"2024-06-08T17:42:18","date_gmt":"2024-06-08T17:42:18","guid":{"rendered":"https:\/\/api.croghan.bank\/about-us\/news\/conozca-al-equipo-de-oak-harbor\/"},"modified":"2026-04-21T21:57:24","modified_gmt":"2026-04-21T21:57:24","slug":"conozca-al-equipo-de-oak-harbor","status":"publish","type":"newsarticle","link":"https:\/\/api.croghan.bank\/es\/about-us\/news\/conozca-al-equipo-de-oak-harbor\/","title":{"rendered":"Conozca al equipo de Oak Harbor"},"content":{"rendered":"","protected":false},"template":"","newsarticlecategory":[84],"class_list":["post-4877","newsarticle","type-newsarticle","status-publish","hentry","newsarticlecategory-noticias-de-finanzas-personales"],"acf":{"modules":[{"acf_fc_layout":"bread_crumb_nav_hero","title":"<h1>Conozca al equipo de Oak Harbor<\/h1>","subtitle":"","content":"","buttons":null,"module_anchor_id":"","module_padding_inner":"noPaddingInner","module_spacing_after":"defaultSpacingAfter"},{"acf_fc_layout":"basic_content","content":"<iframe title=\"Conozca a nuestro equipo de Oak Harbor\" src=\"https:\/\/www.youtube.com\/embed\/0cMkHO-RpRQ\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe>\n\nNuestra ubicaci\u00f3n en Oak Harbor abri\u00f3 sus puertas en 2013. La tripulaci\u00f3n se compromete a brindar servicios personalizados y soluciones financieras. Son excelentes solucionadores de problemas y se esfuerzan por hacer lo mejor para usted en funci\u00f3n de su situaci\u00f3n \u00fanica.  \n\nEl equipo incluye:\n<ul>\n \t<li>Ashley Hansen, <em>vicepresidenta ejecutiva, gerente de \u00e1rea<\/em><\/li>\n \t<li>Susie Shaffer, <em>Gerente de Oficina<\/em><\/li>\n \t<li>Cheyenne Harneck, <em>Banquera Universal II<\/em><\/li>\n \t<li>Abby Baugh, <em>Banquera Universal I<\/em><\/li>\n \t<li>Maddie Goff, <em>Cajera<\/em><\/li>\n \t<li>Carissa Shaffer, <em>Cajera<\/em><\/li>\n \t<li>Trey Witt, <em>Cajero<\/em><\/li>\n \t<li>Bailey Janes, <em>Cajera<\/em><\/li>\n<\/ul>\n\u00a0\n\n\u00a0\n\nAqu\u00ed hay algunos datos divertidos sobre este incre\u00edble grupo:\n<ul>\n \t<li><strong>Ashley<\/strong> participa en carreras de barriles femeninos en rodeos.<\/li>\n \t<li><strong>Susie<\/strong> viaj\u00f3 a ocho estados en un viaje por carretera cuando ten\u00eda 18 a\u00f1os.<\/li>\n \t<li><strong>\u00a1Cheyenne<\/strong> es un serio rat\u00f3n de biblioteca y ley\u00f3 150 libros en 2023!<\/li>\n \t<li>El pulgar verde <strong>de Abby<\/strong> ha dado sus frutos, ya que ahora tiene una planta m\u00e1s grande que ella.<\/li>\n \t<li><strong>Carissa<\/strong> tiene un camale\u00f3n llamado Hugo.<\/li>\n \t<li><strong>Maddie<\/strong> tiene inclinaciones musicales y toc\u00f3 el piano durante 12 a\u00f1os.<\/li>\n \t<li><strong>Trey<\/strong> tiene buen ojo para los detalles y colecciona piedras lisas y conchas.<\/li>\n \t<li><strong>Bailey<\/strong> es una \u00e1vida viajera y dice que su lugar favorito es Juneau, Alaska.<\/li>\n<\/ul>\n\u00a0\n\nObtenga m\u00e1s informaci\u00f3n sobre nuestra <a href=\"https:\/\/www.croghan.com\/oak-harbor\">oficina de Oak Harbor<\/a>.","module_background_color":"white","module_anchor_id":"","module_padding_inner":"noPaddingInner","module_spacing_after":"defaultSpacingAfter"}]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conoce al equipo de Oak Harbor | Abierto desde 2013 | Croghan<\/title>\n<meta name=\"description\" content=\"Ashley Hansen lidera el equipo de Croghan Oak Harbor \u2014 Susie, Cheyenne, Abby, Maddie, Carissa, Trey y Bailey \u2014 ofreciendo servicios bancarios personalizados desde 2013.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conoce al equipo de Oak Harbor | Abierto desde 2013 | Croghan\" \/>\n<meta property=\"og:description\" content=\"Ashley Hansen lidera el equipo de Croghan Oak Harbor \u2014 Susie, Cheyenne, Abby, Maddie, Carissa, Trey y Bailey \u2014 ofreciendo servicios bancarios personalizados desde 2013.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/api.croghan.bank\/es\/about-us\/news\/conozca-al-equipo-de-oak-harbor\/\" \/>\n<meta property=\"og:site_name\" content=\"Banco Croghan sin cabeza\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-21T21:57:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/api.croghan.bank\\\/es\\\/about-us\\\/news\\\/conozca-al-equipo-de-oak-harbor\\\/\",\"url\":\"https:\\\/\\\/api.croghan.bank\\\/es\\\/about-us\\\/news\\\/conozca-al-equipo-de-oak-harbor\\\/\",\"name\":\"Conoce al equipo de Oak Harbor | Abierto desde 2013 | Croghan\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/api.croghan.bank\\\/es\\\/#website\"},\"datePublished\":\"2024-06-08T17:42:18+00:00\",\"dateModified\":\"2026-04-21T21:57:24+00:00\",\"description\":\"Ashley Hansen lidera el equipo de Croghan Oak Harbor \u2014 Susie, Cheyenne, Abby, Maddie, Carissa, Trey y Bailey \u2014 ofreciendo servicios bancarios personalizados desde 2013.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/api.croghan.bank\\\/es\\\/about-us\\\/news\\\/conozca-al-equipo-de-oak-harbor\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/api.croghan.bank\\\/es\\\/about-us\\\/news\\\/conozca-al-equipo-de-oak-harbor\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/api.croghan.bank\\\/es\\\/about-us\\\/news\\\/conozca-al-equipo-de-oak-harbor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hogar\",\"item\":\"https:\\\/\\\/api.croghan.bank\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News Articles\",\"item\":\"https:\\\/\\\/api.croghan.bank\\\/es\\\/about-us\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Conozca al equipo de Oak Harbor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/api.croghan.bank\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/api.croghan.bank\\\/es\\\/\",\"name\":\"Banco Croghan sin cabeza\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/api.croghan.bank\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conoce al equipo de Oak Harbor | Abierto desde 2013 | Croghan","description":"Ashley Hansen lidera el equipo de Croghan Oak Harbor \u2014 Susie, Cheyenne, Abby, Maddie, Carissa, Trey y Bailey \u2014 ofreciendo servicios bancarios personalizados desde 2013.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Conoce al equipo de Oak Harbor | Abierto desde 2013 | Croghan","og_description":"Ashley Hansen lidera el equipo de Croghan Oak Harbor \u2014 Susie, Cheyenne, Abby, Maddie, Carissa, Trey y Bailey \u2014 ofreciendo servicios bancarios personalizados desde 2013.","og_url":"https:\/\/api.croghan.bank\/es\/about-us\/news\/conozca-al-equipo-de-oak-harbor\/","og_site_name":"Banco Croghan sin cabeza","article_modified_time":"2026-04-21T21:57:24+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/api.croghan.bank\/es\/about-us\/news\/conozca-al-equipo-de-oak-harbor\/","url":"https:\/\/api.croghan.bank\/es\/about-us\/news\/conozca-al-equipo-de-oak-harbor\/","name":"Conoce al equipo de Oak Harbor | Abierto desde 2013 | Croghan","isPartOf":{"@id":"https:\/\/api.croghan.bank\/es\/#website"},"datePublished":"2024-06-08T17:42:18+00:00","dateModified":"2026-04-21T21:57:24+00:00","description":"Ashley Hansen lidera el equipo de Croghan Oak Harbor \u2014 Susie, Cheyenne, Abby, Maddie, Carissa, Trey y Bailey \u2014 ofreciendo servicios bancarios personalizados desde 2013.","breadcrumb":{"@id":"https:\/\/api.croghan.bank\/es\/about-us\/news\/conozca-al-equipo-de-oak-harbor\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/api.croghan.bank\/es\/about-us\/news\/conozca-al-equipo-de-oak-harbor\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/api.croghan.bank\/es\/about-us\/news\/conozca-al-equipo-de-oak-harbor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hogar","item":"https:\/\/api.croghan.bank\/es\/"},{"@type":"ListItem","position":2,"name":"News Articles","item":"https:\/\/api.croghan.bank\/es\/about-us\/news\/"},{"@type":"ListItem","position":3,"name":"Conozca al equipo de Oak Harbor"}]},{"@type":"WebSite","@id":"https:\/\/api.croghan.bank\/es\/#website","url":"https:\/\/api.croghan.bank\/es\/","name":"Banco Croghan sin cabeza","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/api.croghan.bank\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/api.croghan.bank\/es\/wp-json\/wp\/v2\/newsarticle\/4877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/api.croghan.bank\/es\/wp-json\/wp\/v2\/newsarticle"}],"about":[{"href":"https:\/\/api.croghan.bank\/es\/wp-json\/wp\/v2\/types\/newsarticle"}],"wp:attachment":[{"href":"https:\/\/api.croghan.bank\/es\/wp-json\/wp\/v2\/media?parent=4877"}],"wp:term":[{"taxonomy":"newsarticlecategory","embeddable":true,"href":"https:\/\/api.croghan.bank\/es\/wp-json\/wp\/v2\/newsarticlecategory?post=4877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}